{"id":3955,"date":"2025-01-17T12:53:03","date_gmt":"2025-01-17T11:53:03","guid":{"rendered":"https:\/\/molinodecasilda.com\/?post_type=product&#038;p=3955"},"modified":"2026-05-11T20:21:33","modified_gmt":"2026-05-11T18:21:33","slug":"estuche-regalo-6-botellas-250-ml-picual-temprano","status":"publish","type":"product","link":"https:\/\/molinodecasilda.com\/en\/producto\/estuche-regalo-6-botellas-250-ml-picual-temprano\/","title":{"rendered":"ESTUCHE REGALO 6 BOTELLAS 250 ML. PICUAL TEMPRANO"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":4700,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[195],"product_tag":[201,205,206,202],"class_list":{"0":"post-3955","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-aove-molino-de-casilda","7":"product_tag-aove","8":"product_tag-cosecha-temprana","9":"product_tag-jaen","10":"product_tag-picual","12":"first","13":"outofstock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ESTUCHE REGALO 6 BOTELLAS 250 ML. PICUAL TEMPRANO - Molino de Casilda<\/title>\n<meta name=\"description\" content=\"Estuche regalo de 6 botellas de aceite de oliva virgen extra temprano de 250 ml. con origen en la Sierra de las Villas de Ja\u00e9n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/molinodecasilda.com\/producto\/estuche-regalo-6-botellas-250-ml-picual-temprano\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ESTUCHE REGALO 6 BOTELLAS 250 ML. PICUAL TEMPRANO - Molino de Casilda\" \/>\n<meta property=\"og:description\" content=\"Estuche regalo de 6 botellas de aceite de oliva virgen extra temprano de 250 ml. con origen en la Sierra de las Villas de Ja\u00e9n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/molinodecasilda.com\/producto\/estuche-regalo-6-botellas-250-ml-picual-temprano\/\" \/>\n<meta property=\"og:site_name\" content=\"Molino de Casilda\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T18:21:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/molinodecasilda.com\/wp-content\/uploads\/2024\/06\/7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/molinodecasilda.com\\\/producto\\\/estuche-regalo-6-botellas-250-ml-picual-temprano\\\/\",\"url\":\"https:\\\/\\\/molinodecasilda.com\\\/producto\\\/estuche-regalo-6-botellas-250-ml-picual-temprano\\\/\",\"name\":\"ESTUCHE REGALO 6 BOTELLAS 250 ML. PICUAL TEMPRANO - Molino de Casilda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/molinodecasilda.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/molinodecasilda.com\\\/producto\\\/estuche-regalo-6-botellas-250-ml-picual-temprano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/molinodecasilda.com\\\/producto\\\/estuche-regalo-6-botellas-250-ml-picual-temprano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/molinodecasilda.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/7.jpg\",\"datePublished\":\"2025-01-17T11:53:03+00:00\",\"dateModified\":\"2026-05-11T18:21:33+00:00\",\"description\":\"Estuche regalo de 6 botellas de aceite de oliva virgen extra temprano de 250 ml. con origen en la Sierra de las Villas de Ja\u00e9n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/molinodecasilda.com\\\/producto\\\/estuche-regalo-6-botellas-250-ml-picual-temprano\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/molinodecasilda.com\\\/producto\\\/estuche-regalo-6-botellas-250-ml-picual-temprano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/molinodecasilda.com\\\/producto\\\/estuche-regalo-6-botellas-250-ml-picual-temprano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/molinodecasilda.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/7.jpg\",\"contentUrl\":\"https:\\\/\\\/molinodecasilda.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/7.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/molinodecasilda.com\\\/producto\\\/estuche-regalo-6-botellas-250-ml-picual-temprano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/molinodecasilda.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/molinodecasilda.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ESTUCHE REGALO 6 BOTELLAS 250 ML. PICUAL TEMPRANO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/molinodecasilda.com\\\/#website\",\"url\":\"https:\\\/\\\/molinodecasilda.com\\\/\",\"name\":\"Molino de Casilda\",\"description\":\"Extra virgin olive oil Online Shop\",\"publisher\":{\"@id\":\"https:\\\/\\\/molinodecasilda.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/molinodecasilda.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/molinodecasilda.com\\\/#organization\",\"name\":\"Molino de Casilda\",\"url\":\"https:\\\/\\\/molinodecasilda.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/molinodecasilda.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/molinodecasilda.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/20181124-logo-molino-casilda-1.png\",\"contentUrl\":\"https:\\\/\\\/molinodecasilda.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/20181124-logo-molino-casilda-1.png\",\"width\":279,\"height\":68,\"caption\":\"Molino de Casilda\"},\"image\":{\"@id\":\"https:\\\/\\\/molinodecasilda.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ESTUCHE REGALO 6 BOTELLAS 250 ML. PICUAL TEMPRANO - Molino de Casilda","description":"Estuche regalo de 6 botellas de aceite de oliva virgen extra temprano de 250 ml. con origen en la Sierra de las Villas de Ja\u00e9n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/molinodecasilda.com\/producto\/estuche-regalo-6-botellas-250-ml-picual-temprano\/","og_locale":"en_US","og_type":"article","og_title":"ESTUCHE REGALO 6 BOTELLAS 250 ML. PICUAL TEMPRANO - Molino de Casilda","og_description":"Estuche regalo de 6 botellas de aceite de oliva virgen extra temprano de 250 ml. con origen en la Sierra de las Villas de Ja\u00e9n","og_url":"https:\/\/molinodecasilda.com\/producto\/estuche-regalo-6-botellas-250-ml-picual-temprano\/","og_site_name":"Molino de Casilda","article_modified_time":"2026-05-11T18:21:33+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/molinodecasilda.com\/wp-content\/uploads\/2024\/06\/7.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/molinodecasilda.com\/producto\/estuche-regalo-6-botellas-250-ml-picual-temprano\/","url":"https:\/\/molinodecasilda.com\/producto\/estuche-regalo-6-botellas-250-ml-picual-temprano\/","name":"ESTUCHE REGALO 6 BOTELLAS 250 ML. PICUAL TEMPRANO - Molino de Casilda","isPartOf":{"@id":"https:\/\/molinodecasilda.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/molinodecasilda.com\/producto\/estuche-regalo-6-botellas-250-ml-picual-temprano\/#primaryimage"},"image":{"@id":"https:\/\/molinodecasilda.com\/producto\/estuche-regalo-6-botellas-250-ml-picual-temprano\/#primaryimage"},"thumbnailUrl":"https:\/\/molinodecasilda.com\/wp-content\/uploads\/2024\/06\/7.jpg","datePublished":"2025-01-17T11:53:03+00:00","dateModified":"2026-05-11T18:21:33+00:00","description":"Estuche regalo de 6 botellas de aceite de oliva virgen extra temprano de 250 ml. con origen en la Sierra de las Villas de Ja\u00e9n","breadcrumb":{"@id":"https:\/\/molinodecasilda.com\/producto\/estuche-regalo-6-botellas-250-ml-picual-temprano\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/molinodecasilda.com\/producto\/estuche-regalo-6-botellas-250-ml-picual-temprano\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/molinodecasilda.com\/producto\/estuche-regalo-6-botellas-250-ml-picual-temprano\/#primaryimage","url":"https:\/\/molinodecasilda.com\/wp-content\/uploads\/2024\/06\/7.jpg","contentUrl":"https:\/\/molinodecasilda.com\/wp-content\/uploads\/2024\/06\/7.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/molinodecasilda.com\/producto\/estuche-regalo-6-botellas-250-ml-picual-temprano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/molinodecasilda.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/molinodecasilda.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"ESTUCHE REGALO 6 BOTELLAS 250 ML. PICUAL TEMPRANO"}]},{"@type":"WebSite","@id":"https:\/\/molinodecasilda.com\/#website","url":"https:\/\/molinodecasilda.com\/","name":"Molino de Casilda","description":"Extra virgin olive oil Online Shop","publisher":{"@id":"https:\/\/molinodecasilda.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/molinodecasilda.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/molinodecasilda.com\/#organization","name":"Molino de Casilda","url":"https:\/\/molinodecasilda.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/molinodecasilda.com\/#\/schema\/logo\/image\/","url":"https:\/\/molinodecasilda.com\/wp-content\/uploads\/2018\/11\/20181124-logo-molino-casilda-1.png","contentUrl":"https:\/\/molinodecasilda.com\/wp-content\/uploads\/2018\/11\/20181124-logo-molino-casilda-1.png","width":279,"height":68,"caption":"Molino de Casilda"},"image":{"@id":"https:\/\/molinodecasilda.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/molinodecasilda.com\/en\/wp-json\/wp\/v2\/product\/3955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/molinodecasilda.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/molinodecasilda.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/molinodecasilda.com\/en\/wp-json\/wp\/v2\/comments?post=3955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/molinodecasilda.com\/en\/wp-json\/wp\/v2\/media\/4700"}],"wp:attachment":[{"href":"https:\/\/molinodecasilda.com\/en\/wp-json\/wp\/v2\/media?parent=3955"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/molinodecasilda.com\/en\/wp-json\/wp\/v2\/product_brand?post=3955"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/molinodecasilda.com\/en\/wp-json\/wp\/v2\/product_cat?post=3955"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/molinodecasilda.com\/en\/wp-json\/wp\/v2\/product_tag?post=3955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}